{"id":46,"date":"2009-06-04T11:18:00","date_gmt":"2009-06-04T11:18:00","guid":{"rendered":"http:\/\/www.centroeducacionintegral.es\/mapas-mentales\/"},"modified":"2009-06-04T11:18:00","modified_gmt":"2009-06-04T11:18:00","slug":"mapas-mentales","status":"publish","type":"post","link":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/mapas-mentales\/","title":{"rendered":"Mapas Mentales"},"content":{"rendered":"<div><a href=\"http:\/\/1.bp.blogspot.com\/_mkcLJTO0tnY\/SivAULDf7yI\/AAAAAAAAAEA\/RCMKkalZAks\/s1600-h\/mapa+colores.gif\"><img decoding=\"async\" src=\"http:\/\/1.bp.blogspot.com\/_mkcLJTO0tnY\/SivAULDf7yI\/AAAAAAAAAEA\/RCMKkalZAks\/s200\/mapa+colores.gif\" alt=\"\" border=\"0\"><\/a>Los Mapas Mentales son una t\u00e9cnica de estudio basada en el <a href=\"http:\/\/centrodeeducacionintegral.blogspot.com\/2009\/06\/pensamiento-irradiante.html\"><span>pensamiento irradiante<\/span><\/a>, desarrollada por Tony Buzan.<\/div>\n<div>El m\u00e9todo consiste en una representaci\u00f3n gr\u00e1fica de un tema, idea o concepto, plasmado en una hoja de papel, empleando dibujos sencillos; escribiendo palabras clave propias, utilizando colores, c\u00f3digos, flechas, de tal manera que la idea principal quede al centro del diagrama y las ideas secundarias fluyan desde el centro como las ramas de un \u00e1rbol.<\/p>\n<p><span>Para qu\u00e9 sirven<\/span><br \/>Los Mapas Mentales sirven para gestionar el flujo de informaci\u00f3n que diariamente utilizamos facilit\u00e1ndonos la organizaci\u00f3n del pensamiento en un esquema sencillo, permitiendo obtener una visi\u00f3n clara y global de las cosas.<\/p>\n<p>Al emplear este sistema exponiendo gr\u00e1ficamente nuestras ideas, desarrollamos y potenciamos las capacidades mentales que poseemos de forma innata, tales como, la concentraci\u00f3n, la l\u00f3gica, la creatividad, la imaginaci\u00f3n, la asociaci\u00f3n de ideas y la memoria.<\/p>\n<p>Este instrumento de an\u00e1lisis, simple y pr\u00e1ctico, permite incrementar el rendimiento personal, la agilidad mental, as\u00ed como tambi\u00e9n la capacidad de asimilar y procesar cualquier tipo de informaci\u00f3n.<\/p>\n<p>Tony Buzan, cient\u00edfico ingl\u00e9s, creador de \u00e9ste m\u00e9todo basado en ideas originales de Leonardo Da Vinci, en su libro Los Mapas Mentales,  dice as\u00ed:<\/p>\n<blockquote><p>\u00abEl Mapa Mental es la expresi\u00f3n del pensamiento irradiante y, por tanto, una funci\u00f3n natural de la mente. Es una t\u00e9cnica gr\u00e1fica que nos ofrece una llave maestra para acceder al potencial de nuestro cerebro. Se puede aplicar a todos los aspectos de la vida, de modo que una mejor\u00eda en el aprendizaje y una mayor claridad de pensamiento pueden reforzar el trabajo del hombre\u00bb.<\/p><\/blockquote>\n<p><span>C\u00f3mo hacer un Mapa Mental<\/span><span><span><br \/><\/span><\/span><\/p>\n<div>\n<blockquote><p><span><a href=\"http:\/\/www.youtube.com\/watch?v=DSvCrWL7CHs&#038;eurl=http%3A%2F%2Fel50.com%2F2007%2F08%2F14%2Fmapas-mentales-una-forma-de-organizar-y-estimular-las-ideas%2F&#038;feature=player_embedded\"><span>Pincha aqu\u00ed para ver el video<\/span><\/a><\/span><\/p><\/blockquote>\n<\/div>\n<p><span>Aplicaciones m\u00e1s usuales<\/span><\/div>\n<ul>\n<li>Organizar informaci\u00f3n<\/li>\n<li>Solucionar problemas<\/li>\n<li>Producir y aclarar ideas<\/li>\n<li>Estudiar<\/li>\n<li>Concentraci\u00f3n<\/li>\n<li>Estimular la imaginaci\u00f3n y creatividad<\/li>\n<li>Mejorar la comunicaci\u00f3n en un equipo de trabajo<\/li>\n<li>Planificaci\u00f3n y programaci\u00f3n de actividades<\/li>\n<li>Toma de decisiones<\/li>\n<li>Lluvia de ideas<\/li>\n<\/ul>\n<p>Fuente: <span>BUZAN, Tony (1996): <\/span><a href=\"http:\/\/www.buzanworld.com\/Mind_Maps.htm\">El libro de los mapas mentales: C\u00f3mo utilizar al m\u00e1ximo las capacidades de la mente.<\/a> <span>Ed. Urano. Barcelona.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Mapas Mentales son una t&eacute;cnica de estudio basada en el pensamiento irradiante, desarrollada por Tony Buzan. El m&eacute;todo consiste en una representaci&oacute;n gr&aacute;fica de un tema, idea o concepto, plasmado en una hoja de papel, empleando dibujos sencillos; escribiendo &hellip; <a href=\"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/mapas-mentales\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,22],"tags":[],"class_list":["post-46","post","type-post","status-publish","format-standard","hentry","category-aprender-a-aprender","category-tecnicas-de-estudio"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"teresalv\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/mapas-mentales\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Centro de Educaci\u00f3n Integral | Otro sitio realizado con WordPress\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Mapas Mentales | Centro de Educaci\u00f3n Integral\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/mapas-mentales\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2009-06-04T11:18:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2009-06-04T11:18:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Mapas Mentales | Centro de Educaci\u00f3n Integral\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/mapas-mentales\\\/#article\",\"name\":\"Mapas Mentales | Centro de Educaci\\u00f3n Integral\",\"headline\":\"Mapas Mentales\",\"author\":{\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/author\\\/teresalv\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/1.bp.blogspot.com\\\/_mkcLJTO0tnY\\\/SivAULDf7yI\\\/AAAAAAAAAEA\\\/RCMKkalZAks\\\/s200\\\/mapa+colores.gif\",\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/mapas-mentales\\\/#articleImage\"},\"datePublished\":\"2009-06-04T11:18:00+00:00\",\"dateModified\":\"2009-06-04T11:18:00+00:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/mapas-mentales\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/mapas-mentales\\\/#webpage\"},\"articleSection\":\"aprender a aprender, t\\u00e9cnicas de estudio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/mapas-mentales\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/category\\\/aprender-a-aprender\\\/#listItem\",\"name\":\"aprender a aprender\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/category\\\/aprender-a-aprender\\\/#listItem\",\"position\":2,\"name\":\"aprender a aprender\",\"item\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/category\\\/aprender-a-aprender\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/mapas-mentales\\\/#listItem\",\"name\":\"Mapas Mentales\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/mapas-mentales\\\/#listItem\",\"position\":3,\"name\":\"Mapas Mentales\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/category\\\/aprender-a-aprender\\\/#listItem\",\"name\":\"aprender a aprender\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/#organization\",\"name\":\"Centro de Educaci\\u00f3n Integral\",\"description\":\"Otro sitio realizado con WordPress\",\"url\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/author\\\/teresalv\\\/#author\",\"url\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/author\\\/teresalv\\\/\",\"name\":\"teresalv\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/mapas-mentales\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7b75383ba1f746757945a23daafd31da5e564d7173cc7790ec1447c581ba32b?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"teresalv\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/mapas-mentales\\\/#webpage\",\"url\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/mapas-mentales\\\/\",\"name\":\"Mapas Mentales | Centro de Educaci\\u00f3n Integral\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/mapas-mentales\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/author\\\/teresalv\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/author\\\/teresalv\\\/#author\"},\"datePublished\":\"2009-06-04T11:18:00+00:00\",\"dateModified\":\"2009-06-04T11:18:00+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/#website\",\"url\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/\",\"name\":\"Centro de Educaci\\u00f3n Integral\",\"description\":\"Otro sitio realizado con WordPress\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.teresalv.com\\\/centrodeeducacionintegral\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Mapas Mentales | Centro de Educaci\u00f3n Integral","description":"","canonical_url":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/mapas-mentales\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/mapas-mentales\/#article","name":"Mapas Mentales | Centro de Educaci\u00f3n Integral","headline":"Mapas Mentales","author":{"@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/author\/teresalv\/#author"},"publisher":{"@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/1.bp.blogspot.com\/_mkcLJTO0tnY\/SivAULDf7yI\/AAAAAAAAAEA\/RCMKkalZAks\/s200\/mapa+colores.gif","@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/mapas-mentales\/#articleImage"},"datePublished":"2009-06-04T11:18:00+00:00","dateModified":"2009-06-04T11:18:00+00:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/mapas-mentales\/#webpage"},"isPartOf":{"@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/mapas-mentales\/#webpage"},"articleSection":"aprender a aprender, t\u00e9cnicas de estudio"},{"@type":"BreadcrumbList","@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/mapas-mentales\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral#listItem","position":1,"name":"Inicio","item":"https:\/\/www.teresalv.com\/centrodeeducacionintegral","nextItem":{"@type":"ListItem","@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/category\/aprender-a-aprender\/#listItem","name":"aprender a aprender"}},{"@type":"ListItem","@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/category\/aprender-a-aprender\/#listItem","position":2,"name":"aprender a aprender","item":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/category\/aprender-a-aprender\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/mapas-mentales\/#listItem","name":"Mapas Mentales"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/mapas-mentales\/#listItem","position":3,"name":"Mapas Mentales","previousItem":{"@type":"ListItem","@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/category\/aprender-a-aprender\/#listItem","name":"aprender a aprender"}}]},{"@type":"Organization","@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/#organization","name":"Centro de Educaci\u00f3n Integral","description":"Otro sitio realizado con WordPress","url":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/"},{"@type":"Person","@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/author\/teresalv\/#author","url":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/author\/teresalv\/","name":"teresalv","image":{"@type":"ImageObject","@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/mapas-mentales\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c7b75383ba1f746757945a23daafd31da5e564d7173cc7790ec1447c581ba32b?s=96&d=mm&r=g","width":96,"height":96,"caption":"teresalv"}},{"@type":"WebPage","@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/mapas-mentales\/#webpage","url":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/mapas-mentales\/","name":"Mapas Mentales | Centro de Educaci\u00f3n Integral","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/#website"},"breadcrumb":{"@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/mapas-mentales\/#breadcrumblist"},"author":{"@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/author\/teresalv\/#author"},"creator":{"@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/author\/teresalv\/#author"},"datePublished":"2009-06-04T11:18:00+00:00","dateModified":"2009-06-04T11:18:00+00:00"},{"@type":"WebSite","@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/#website","url":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/","name":"Centro de Educaci\u00f3n Integral","description":"Otro sitio realizado con WordPress","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Centro de Educaci\u00f3n Integral | Otro sitio realizado con WordPress","og:type":"article","og:title":"Mapas Mentales | Centro de Educaci\u00f3n Integral","og:url":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/mapas-mentales\/","article:published_time":"2009-06-04T11:18:00+00:00","article:modified_time":"2009-06-04T11:18:00+00:00","twitter:card":"summary","twitter:title":"Mapas Mentales | Centro de Educaci\u00f3n Integral"},"aioseo_meta_data":{"post_id":"46","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-02-15 18:49:54","updated":"2025-06-23 09:08:20","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.teresalv.com\/centrodeeducacionintegral\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/category\/aprender-a-aprender\/\" title=\"aprender a aprender\">aprender a aprender<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMapas Mentales\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www.teresalv.com\/centrodeeducacionintegral"},{"label":"aprender a aprender","link":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/category\/aprender-a-aprender\/"},{"label":"Mapas Mentales","link":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/mapas-mentales\/"}],"_links":{"self":[{"href":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/wp-json\/wp\/v2\/posts\/46","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/wp-json\/wp\/v2\/comments?post=46"}],"version-history":[{"count":0,"href":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/wp-json\/wp\/v2\/posts\/46\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/wp-json\/wp\/v2\/media?parent=46"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/wp-json\/wp\/v2\/categories?post=46"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.teresalv.com\/centrodeeducacionintegral\/wp-json\/wp\/v2\/tags?post=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}